{"id":1247,"date":"2021-08-27T17:02:30","date_gmt":"2021-08-27T15:02:30","guid":{"rendered":"https:\/\/boesling.com\/bo2021\/data-privacy-policy\/"},"modified":"2022-02-28T17:33:15","modified_gmt":"2022-02-28T16:33:15","slug":"datenschutzerklaerung","status":"publish","type":"page","link":"https:\/\/boesling.com\/de\/datenschutzerklaerung\/","title":{"rendered":"Datenschutzerkl\u00e4rung"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<div id='dsgvoaio_policy_wrap'><div class='dsgvo_aio_policy'><h2>Datenschutzerkl\u00e4rung<\/h2>\n<p>Stand: 01.03.2022<\/p>\n<p>Wir freuen uns sehr \u00fcber Ihr Interesse an unserem Unternehmen. Datenschutz hat einen besonders hohen Stellenwert f\u00fcr die Gesch\u00e4ftsleitung. Eine Nutzung der Internetseiten ist grunds\u00e4tzlich ohne jede Angabe personenbezogener Daten m\u00f6glich. Sofern eine betroffene Person besondere Services unseres Unternehmens \u00fcber unsere Internetseite in Anspruch nehmen m\u00f6chte, k\u00f6nnte jedoch eine Verarbeitung personenbezogener Daten erforderlich werden. Ist die Verarbeitung personenbezogener Daten erforderlich und besteht f\u00fcr eine solche Verarbeitung keine gesetzliche Grundlage, holen wir generell eine Einwilligung der betroffenen Person ein.<\/p>\n<p>Die Verarbeitung personenbezogener Daten, beispielsweise des Namens, der Anschrift, E-Mail-Adresse oder Telefonnummer einer betroffenen Person, erfolgt stets im Einklang mit der Datenschutz-Grundverordnung und in \u00dcbereinstimmung mit den f\u00fcr uns geltenden landesspezifischen Datenschutzbestimmungen. Mittels dieser Datenschutzerkl\u00e4rung m\u00f6chte unser Unternehmen die \u00d6ffentlichkeit \u00fcber Art, Umfang und Zweck der von uns erhobenen, genutzten und verarbeiteten personenbezogenen Daten informieren. Ferner werden betroffene Personen mittels dieser Datenschutzerkl\u00e4rung \u00fcber die ihnen zustehenden Rechte aufgekl\u00e4rt.<\/p>\n<p>Wir haben als f\u00fcr die Verarbeitung Verantwortlicher zahlreiche technische und organisatorische Ma\u00dfnahmen umgesetzt, um einen m\u00f6glichst l\u00fcckenlosen Schutz der \u00fcber diese Internetseite verarbeiteten personenbezogenen Daten sicherzustellen. Dennoch k\u00f6nnen Internetbasierte Daten\u00fcbertragungen grunds\u00e4tzlich Sicherheitsl\u00fccken aufweisen, sodass ein absoluter Schutz nicht gew\u00e4hrleistet werden kann. Aus diesem Grund steht es jeder betroffenen Person frei, personenbezogene Daten auch auf alternativen Wegen, beispielsweise telefonisch, an uns zu \u00fcbermitteln.<\/p>\n<h4>Begriffsbestimmungen<\/h4>\n<p>Die Datenschutzerkl\u00e4rung beruht auf den Begrifflichkeiten, die durch den Europ\u00e4ischen Richtlinien- und Verordnungsgeber beim Erlass der Datenschutz-Grundverordnung (DSGVO) verwendet wurden. Unsere Datenschutzerkl\u00e4rung soll sowohl f\u00fcr die \u00d6ffentlichkeit als auch f\u00fcr unsere Kunden und Gesch\u00e4ftspartner einfach lesbar und verst\u00e4ndlich sein. Um dies zu gew\u00e4hrleisten, m\u00f6chten wir vorab die verwendeten Begrifflichkeiten erl\u00e4utern.<\/p>\n<p>Wir verwenden in dieser Datenschutzerkl\u00e4rung unter anderem die folgenden Begriffe:<\/p>\n<ul style=\"list-style: none;\">\n<li>\n<h4>a) personenbezogene Daten<\/h4>\n<p>Personenbezogene Daten sind alle Informationen, die sich auf eine identifizierte oder identifizierbare nat\u00fcrliche Person (im Folgenden \"betroffene Person\") beziehen. Als identifizierbar wird eine nat\u00fcrliche Person angesehen, die direkt oder indirekt, insbesondere mittels Zuordnung zu einer Kennung wie einem Namen, zu einer Kennnummer, zu Standortdaten, zu einer Online-Kennung oder zu einem oder mehreren besonderen Merkmalen, die Ausdruck der physischen, physiologischen, genetischen, psychischen, wirtschaftlichen, kulturellen oder sozialen Identit\u00e4t dieser nat\u00fcrlichen Person sind, identifiziert werden kann.<\/li>\n<li>\n<h4>b) betroffene Person<\/h4>\n<p>Betroffene Person ist jede identifizierte oder identifizierbare nat\u00fcrliche Person, deren personenbezogene Daten von dem f\u00fcr die Verarbeitung Verantwortlichen verarbeitet werden.<\/li>\n<li>\n<h4>c) Verarbeitung<\/h4>\n<p>Verarbeitung ist jeder mit oder ohne Hilfe automatisierter Verfahren ausgef\u00fchrte Vorgang oder jede solche Vorgangsreihe im Zusammenhang mit personenbezogenen Daten wie das Erheben, das Erfassen, die Organisation, das Ordnen, die Speicherung, die Anpassung oder Ver\u00e4nderung, das Auslesen, das Abfragen, die Verwendung, die Offenlegung durch \u00dcbermittlung, Verbreitung oder eine andere Form der Bereitstellung, den Abgleich oder die Verkn\u00fcpfung, die Einschr\u00e4nkung, das L\u00f6schen oder die Vernichtung.<\/li>\n<li>\n<h4>d) Einschr\u00e4nkung der Verarbeitung<\/h4>\n<p>Einschr\u00e4nkung der Verarbeitung ist die Markierung gespeicherter personenbezogener Daten mit dem Ziel, ihre k\u00fcnftige Verarbeitung einzuschr\u00e4nken.<\/li>\n<li>\n<h4>e) Profiling<\/h4>\n<p>Profiling ist jede Art der automatisierten Verarbeitung personenbezogener Daten, die darin besteht, dass diese personenbezogenen Daten verwendet werden, um bestimmte pers\u00f6nliche Aspekte, die sich auf eine nat\u00fcrliche Person beziehen, zu bewerten, insbesondere, um Aspekte bez\u00fcglich Arbeitsleistung, wirtschaftlicher Lage, Gesundheit, pers\u00f6nlicher Vorlieben, Interessen, Zuverl\u00e4ssigkeit, Verhalten, Aufenthaltsort oder Ortswechsel dieser nat\u00fcrlichen Person zu analysieren oder vorherzusagen.<\/li>\n<li>\n<h4>f) Pseudonymisierung<\/h4>\n<p>Pseudonymisierung ist die Verarbeitung personenbezogener Daten in einer Weise, auf welche die personenbezogenen Daten ohne Hinzuziehung zus\u00e4tzlicher Informationen nicht mehr einer spezifischen betroffenen Person zugeordnet werden k\u00f6nnen, sofern diese zus\u00e4tzlichen Informationen gesondert aufbewahrt werden und technischen und organisatorischen Ma\u00dfnahmen unterliegen, die gew\u00e4hrleisten, dass die personenbezogenen Daten nicht einer identifizierten oder identifizierbaren nat\u00fcrlichen Person zugewiesen werden.<\/li>\n<li>\n<h4>g) Verantwortlicher oder f\u00fcr die Verarbeitung Verantwortlicher<\/h4>\n<p>Verantwortlicher oder f\u00fcr die Verarbeitung Verantwortlicher ist die nat\u00fcrliche oder juristische Person, Beh\u00f6rde, Einrichtung oder andere Stelle, die allein oder gemeinsam mit anderen \u00fcber die Zwecke und Mittel der Verarbeitung von personenbezogenen Daten entscheidet. Sind die Zwecke und Mittel dieser Verarbeitung durch das Unionsrecht oder das Recht der Mitgliedstaaten vorgegeben, so kann der Verantwortliche beziehungsweise k\u00f6nnen die bestimmten Kriterien seiner Benennung nach dem Unionsrecht oder dem Recht der Mitgliedstaaten vorgesehen werden.<\/li>\n<li>\n<h4>h) Auftragsverarbeiter<\/h4>\n<p>Auftragsverarbeiter ist eine nat\u00fcrliche oder juristische Person, Beh\u00f6rde, Einrichtung oder andere Stelle, die personenbezogene Daten im Auftrag des Verantwortlichen verarbeitet.<\/li>\n<li>\n<h4>i) Empf\u00e4nger<\/h4>\n<p>Empf\u00e4nger ist eine nat\u00fcrliche oder juristische Person, Beh\u00f6rde, Einrichtung oder andere Stelle, der personenbezogene Daten offengelegt werden, unabh\u00e4ngig davon, ob es sich bei ihr um einen Dritten handelt oder nicht. Beh\u00f6rden, die im Rahmen eines bestimmten Untersuchungsauftrags nach dem Unionsrecht oder dem Recht der Mitgliedstaaten m\u00f6glicherweise personenbezogene Daten erhalten, gelten jedoch nicht als Empf\u00e4nger.<\/li>\n<li>\n<h4>j) Dritter<\/h4>\n<p>Dritter ist eine nat\u00fcrliche oder juristische Person, Beh\u00f6rde, Einrichtung oder andere Stelle au\u00dfer der betroffenen Person, dem Verantwortlichen, dem Auftragsverarbeiter und den Personen, die unter der unmittelbaren Verantwortung des Verantwortlichen oder des Auftragsverarbeiters befugt sind, die personenbezogenen Daten zu verarbeiten.<\/li>\n<li>\n<h4>k) Einwilligung<\/h4>\n<p>Einwilligung ist jede von der betroffenen Person freiwillig f\u00fcr den bestimmten Fall in informierter Weise und unmissverst\u00e4ndlich abgegebene Willensbekundung in Form einer Erkl\u00e4rung oder einer sonstigen eindeutigen best\u00e4tigenden Handlung, mit der die betroffene Person zu verstehen gibt, dass sie mit der Verarbeitung der sie betreffenden personenbezogenen Daten einverstanden ist.<\/li>\n<\/ul>\n<h4>Name und Anschrift des f\u00fcr die Verarbeitung Verantwortlichen<\/h4>\n<p>Verantwortlicher im Sinne der Datenschutz-Grundverordnung, sonstiger in den Mitgliedstaaten der Europ\u00e4ischen Union geltenden Datenschutzgesetze und anderer Bestimmungen mit datenschutzrechtlichem Charakter ist:<\/p>\n<p>boesling IP Rechtsanw\u00e4lte PartG mbB<\/p>\n<p>Heimhuder Stra\u00dfe 79<\/p>\n<p>D-20148 Hamburg - Germany<\/p>\n<p><p>Telefon:&nbsp;+ 49 40 5247624-0<\/p>\n<p><p>Fax:&nbsp;+ 49 40 5247624-25<\/p><\/p>\n<p><p>E-Mail:&nbsp;office@boesling.com<\/p><\/p>\n<p><p>UST-ID:&nbsp;DE304417817<\/p><\/p>\n<h4>Cookies<\/h4>\n<p>Die Internetseiten verwenden Cookies. Cookies sind Textdateien, welche \u00fcber einen Internetbrowser auf einem Computersystem abgelegt und gespeichert werden.<\/p>\n<p>Zahlreiche Internetseiten und Server verwenden Cookies. Viele Cookies enthalten eine sogenannte Cookie-ID. Eine Cookie-ID ist eine eindeutige Kennung des Cookies. Sie besteht aus einer Zeichenfolge, durch welche Internetseiten und Server dem konkreten Internetbrowser zugeordnet werden k\u00f6nnen, in dem das Cookie gespeichert wurde. Dies erm\u00f6glicht es den besuchten Internetseiten und Servern, den individuellen Browser der betroffenen Person von anderen Internetbrowsern, die andere Cookies enthalten, zu unterscheiden. Ein bestimmter Internetbrowser kann \u00fcber die eindeutige Cookie-ID wiedererkannt und identifiziert werden.<\/p>\n<p>Durch den Einsatz von Cookies kann den Nutzern dieser Internetseite nutzerfreundlichere Services bereitstellen, die ohne die Cookie-Setzung nicht m\u00f6glich w\u00e4ren.<\/p>\n<p>Mittels eines Cookies k\u00f6nnen die Informationen und Angebote auf unserer Internetseite im Sinne des Benutzers optimiert werden. Cookies erm\u00f6glichen uns, wie bereits erw\u00e4hnt, die Benutzer unserer Internetseite wiederzuerkennen. Zweck dieser Wiedererkennung ist es, den Nutzern die Verwendung unserer Internetseite zu erleichtern. Der Benutzer einer Internetseite, die Cookies verwendet, muss beispielsweise nicht bei jedem Besuch der Internetseite erneut seine Zugangsdaten eingeben, weil dies von der Internetseite und dem auf dem Computersystem des Benutzers abgelegten Cookie \u00fcbernommen wird. Ein weiteres Beispiel ist das Cookie eines Warenkorbes im Online-Shop. Der Online-Shop merkt sich die Artikel, die ein Kunde in den virtuellen Warenkorb gelegt hat, \u00fcber ein Cookie.<\/p>\n<p>Die betroffene Person kann die Setzung von Cookies durch unsere Internetseite jederzeit mittels einer entsprechenden Einstellung des genutzten Internetbrowsers verhindern und damit der Setzung von Cookies dauerhaft widersprechen. Ferner k\u00f6nnen bereits gesetzte Cookies jederzeit \u00fcber einen Internetbrowser oder andere Softwareprogramme gel\u00f6scht werden. Dies ist in allen g\u00e4ngigen Internetbrowsern m\u00f6glich. Deaktiviert die betroffene Person die Setzung von Cookies in dem genutzten Internetbrowser, sind unter Umst\u00e4nden nicht alle Funktionen unserer Internetseite vollumf\u00e4nglich nutzbar.<\/p>\n<h4>Erfassung von allgemeinen Daten und Informationen<\/h4>\n<p>Die Internetseite erfasst mit jedem Aufruf der Internetseite durch eine betroffene Person oder ein automatisiertes System eine Reihe von allgemeinen Daten und Informationen. Diese allgemeinen Daten und Informationen werden in den Logfiles des Servers gespeichert. Erfasst werden k\u00f6nnen die (1) verwendeten Browsertypen und Versionen, (2) das vom zugreifenden System verwendete Betriebssystem, (3) die Internetseite, von welcher ein zugreifendes System auf unsere Internetseite gelangt (sogenannte Referrer), (4) die Unterwebseiten, welche \u00fcber ein zugreifendes System auf unserer Internetseite angesteuert werden, (5) das Datum und die Uhrzeit eines Zugriffs auf die Internetseite, (6) eine Internet-Protokoll-Adresse (IP-Adresse), (7) der Internet-Service-Provider des zugreifenden Systems und (8) sonstige \u00e4hnliche Daten und Informationen, die der Gefahrenabwehr im Falle von Angriffen auf unsere informationstechnologischen Systeme dienen.<\/p>\n<p>Bei der Nutzung dieser allgemeinen Daten und Informationen ziehen wird keine R\u00fcckschl\u00fcsse auf die betroffene Person. Diese Informationen werden vielmehr ben\u00f6tigt, um (1) die Inhalte unserer Internetseite korrekt auszuliefern, (2) die Inhalte unserer Internetseite sowie die Werbung f\u00fcr diese zu optimieren, (3) die dauerhafte Funktionsf\u00e4higkeit unserer informationstechnologischen Systeme und der Technik unserer Internetseite zu gew\u00e4hrleisten sowie (4) um Strafverfolgungsbeh\u00f6rden im Falle eines Cyberangriffes die zur Strafverfolgung notwendigen Informationen bereitzustellen. Diese anonym erhobenen Daten und Informationen werden durch uns daher einerseits statistisch und ferner mit dem Ziel ausgewertet, den Datenschutz und die Datensicherheit in unserem Unternehmen zu erh\u00f6hen, um letztlich ein optimales Schutzniveau f\u00fcr die von uns verarbeiteten personenbezogenen Daten sicherzustellen. Die anonymen Daten der Server-Logfiles werden getrennt von allen durch eine betroffene Person angegebenen personenbezogenen Daten gespeichert.<\/p>\n<h4>Registrierung auf unserer Internetseite<\/h4>\n<p>Die betroffene Person hat die M\u00f6glichkeit, sich auf der Internetseite des f\u00fcr die Verarbeitung Verantwortlichen unter Angabe von personenbezogenen Daten zu registrieren. Welche personenbezogenen Daten dabei an den f\u00fcr die Verarbeitung Verantwortlichen \u00fcbermittelt werden, ergibt sich aus der jeweiligen Eingabemaske, die f\u00fcr die Registrierung verwendet wird. Die von der betroffenen Person eingegebenen personenbezogenen Daten werden ausschlie\u00dflich f\u00fcr die interne Verwendung bei dem f\u00fcr die Verarbeitung Verantwortlichen und f\u00fcr eigene Zwecke erhoben und gespeichert. Der f\u00fcr die Verarbeitung Verantwortliche kann die Weitergabe an einen oder mehrere Auftragsverarbeiter, beispielsweise einen Paketdienstleister, veranlassen, der die personenbezogenen Daten ebenfalls ausschlie\u00dflich f\u00fcr eine interne Verwendung, die dem f\u00fcr die Verarbeitung Verantwortlichen zuzurechnen ist, nutzt.<\/p>\n<p>Durch eine Registrierung auf der Internetseite des f\u00fcr die Verarbeitung Verantwortlichen wird ferner die vom Internet-Service-Provider (ISP) der betroffenen Person vergebene IP-Adresse, das Datum sowie die Uhrzeit der Registrierung gespeichert. Die Speicherung dieser Daten erfolgt vor dem Hintergrund, dass nur so der Missbrauch unserer Dienste verhindert werden kann, und diese Daten im Bedarfsfall erm\u00f6glichen, begangene Straftaten aufzukl\u00e4ren. Insofern ist die Speicherung dieser Daten zur Absicherung des f\u00fcr die Verarbeitung Verantwortlichen erforderlich. Eine Weitergabe dieser Daten an Dritte erfolgt grunds\u00e4tzlich nicht, sofern keine gesetzliche Pflicht zur Weitergabe besteht oder die Weitergabe der Strafverfolgung dient.<\/p>\n<p>Die Registrierung der betroffenen Person unter freiwilliger Angabe personenbezogener Daten dient dem f\u00fcr die Verarbeitung Verantwortlichen dazu, der betroffenen Person Inhalte oder Leistungen anzubieten, die aufgrund der Natur der Sache nur registrierten Benutzern angeboten werden k\u00f6nnen. Registrierten Personen steht die M\u00f6glichkeit frei, die bei der Registrierung angegebenen personenbezogenen Daten jederzeit abzu\u00e4ndern oder vollst\u00e4ndig aus dem Datenbestand des f\u00fcr die Verarbeitung Verantwortlichen l\u00f6schen zu lassen.<\/p>\n<p>Der f\u00fcr die Verarbeitung Verantwortliche erteilt jeder betroffenen Person jederzeit auf Anfrage Auskunft dar\u00fcber, welche personenbezogenen Daten \u00fcber die betroffene Person gespeichert sind. Ferner berichtigt oder l\u00f6scht der f\u00fcr die Verarbeitung Verantwortliche personenbezogene Daten auf Wunsch oder Hinweis der betroffenen Person, soweit dem keine gesetzlichen Aufbewahrungspflichten entgegenstehen. Die Gesamtheit der Mitarbeiter des f\u00fcr die Verarbeitung Verantwortlichen stehen der betroffenen Person in diesem Zusammenhang als Ansprechpartner zur Verf\u00fcgung.<\/p>\n<h4>Kontaktm\u00f6glichkeit \u00fcber die Internetseite<\/h4>\n<p>Die Internetseite enth\u00e4lt aufgrund von gesetzlichen Vorschriften Angaben, die eine schnelle elektronische Kontaktaufnahme zu unserem Unternehmen sowie eine unmittelbare Kommunikation mit uns erm\u00f6glichen, was ebenfalls eine allgemeine Adresse der sogenannten elektronischen Post (E-Mail-Adresse) umfasst. Sofern eine betroffene Person per E-Mail oder \u00fcber ein Kontaktformular den Kontakt mit dem f\u00fcr die Verarbeitung Verantwortlichen aufnimmt, werden die von der betroffenen Person \u00fcbermittelten personenbezogenen Daten automatisch gespeichert. Solche auf freiwilliger Basis von einer betroffenen Person an den f\u00fcr die Verarbeitung Verantwortlichen \u00fcbermittelten personenbezogenen Daten werden f\u00fcr Zwecke der Bearbeitung oder der Kontaktaufnahme zur betroffenen Person gespeichert. Es erfolgt keine Weitergabe dieser personenbezogenen Daten an Dritte.<\/p>\n<h4>Hosting<\/h4>\n<p>Die von uns in Anspruch genommenen Hosting-Leistungen dienen der Zurverf\u00fcgungstellung der folgenden Leistungen: Infrastruktur- und Plattformdienstleistungen, Rechenkapazit\u00e4t, Speicherplatz und Datenbankdienste, Sicherheitsleistungen sowie technische Wartungsleistungen, die wir zum Zwecke des Betriebs dieses Onlineangebotes einsetzen.<\/p>\n<p>Hierbei verarbeiten wir, bzw. unser Hostinganbieter Bestandsdaten, Kontaktdaten, Inhaltsdaten, Vertragsdaten, Nutzungsdaten, Meta- und Kommunikationsdaten von Kunden, Interessenten und Besuchern dieses Onlineangebotes auf Grundlage unserer berechtigten Interessen an einer effizienten und sicheren Zurverf\u00fcgungstellung dieses Onlineangebotes gem. Art. 6 Abs. 1 lit. f DSGVO i.V.m. Art. 28 DSGVO (Abschluss Auftragsverarbeitungsvertrag).<\/p>\n<h4>Routinem\u00e4\u00dfige L\u00f6schung und Sperrung von personenbezogenen Daten<\/h4>\n<p>Der f\u00fcr die Verarbeitung Verantwortliche verarbeitet und speichert personenbezogene Daten der betroffenen Person nur f\u00fcr den Zeitraum, der zur Erreichung des Speicherungszwecks erforderlich ist oder sofern dies durch den Europ\u00e4ischen Richtlinien- und Verordnungsgeber oder einen anderen Gesetzgeber in Gesetzen oder Vorschriften, welchen der f\u00fcr die Verarbeitung Verantwortliche unterliegt, vorgesehen wurde.<\/p>\n<p>Entf\u00e4llt der Speicherungszweck oder l\u00e4uft eine vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber oder einem anderen zust\u00e4ndigen Gesetzgeber vorgeschriebene Speicherfrist ab, werden die personenbezogenen Daten routinem\u00e4\u00dfig und entsprechend den gesetzlichen Vorschriften gesperrt oder gel\u00f6scht.<\/p>\n<h4>Rechte der betroffenen Person<\/h4>\n<ul style=\"list-style: none;\">\n<li>\n<h4>a) Recht auf Best\u00e4tigung<\/h4>\n<p>Jede betroffene Person hat das vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber einger\u00e4umte Recht, von dem f\u00fcr die Verarbeitung Verantwortlichen eine Best\u00e4tigung dar\u00fcber zu verlangen, ob sie betreffende personenbezogene Daten verarbeitet werden. M\u00f6chte eine betroffene Person dieses Best\u00e4tigungsrecht in Anspruch nehmen, kann sie sich hierzu jederzeit an einen Mitarbeiter des f\u00fcr die Verarbeitung Verantwortlichen wenden.<\/li>\n<li>\n<h4>b) Recht auf Auskunft<\/h4>\n<p>Jede von der Verarbeitung personenbezogener Daten betroffene Person hat das vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber gew\u00e4hrte Recht, jederzeit von dem f\u00fcr die Verarbeitung Verantwortlichen unentgeltliche Auskunft \u00fcber die zu seiner Person gespeicherten personenbezogenen Daten und eine Kopie dieser Auskunft zu erhalten. Ferner hat der Europ\u00e4ische Richtlinien- und Verordnungsgeber der betroffenen Person Auskunft \u00fcber folgende Informationen zugestanden:<\/p>\n<ul style=\"list-style: none;\">\n<li>die Verarbeitungszwecke<\/li>\n<li>die Kategorien personenbezogener Daten, die verarbeitet werden<\/li>\n<li>die Empf\u00e4nger oder Kategorien von Empf\u00e4ngern, gegen\u00fcber denen die personenbezogenen Daten offengelegt worden sind oder noch offengelegt werden, insbesondere bei Empf\u00e4ngern in Drittl\u00e4ndern oder bei internationalen Organisationen<\/li>\n<li>falls m\u00f6glich die geplante Dauer, f\u00fcr die die personenbezogenen Daten gespeichert werden, oder, falls dies nicht m\u00f6glich ist, die Kriterien f\u00fcr die Festlegung dieser Dauer<\/li>\n<li>das Bestehen eines Rechts auf Berichtigung oder L\u00f6schung der sie betreffenden personenbezogenen Daten oder auf Einschr\u00e4nkung der Verarbeitung durch den Verantwortlichen oder eines Widerspruchsrechts gegen diese Verarbeitung<\/li>\n<li>das Bestehen eines Beschwerderechts bei einer Aufsichtsbeh\u00f6rde<\/li>\n<li>wenn die personenbezogenen Daten nicht bei der betroffenen Person erhoben werden: Alle verf\u00fcgbaren Informationen \u00fcber die Herkunft der Daten<\/li>\n<li>das Bestehen einer automatisierten Entscheidungsfindung einschlie\u00dflich Profiling gem\u00e4\u00df Artikel 22 Abs.1 und 4 DSGVO und \u2014 zumindest in diesen F\u00e4llen \u2014 aussagekr\u00e4ftige Informationen \u00fcber die involvierte Logik sowie die Tragweite und die angestrebten Auswirkungen einer derartigen Verarbeitung f\u00fcr die betroffene Person<\/li>\n<\/ul>\n<p>Ferner steht der betroffenen Person ein Auskunftsrecht dar\u00fcber zu, ob personenbezogene Daten an ein Drittland oder an eine internationale Organisation \u00fcbermittelt wurden. Sofern dies der Fall ist, so steht der betroffenen Person im \u00dcbrigen das Recht zu, Auskunft \u00fcber die geeigneten Garantien im Zusammenhang mit der \u00dcbermittlung zu erhalten.<\/p>\n<p>M\u00f6chte eine betroffene Person dieses Auskunftsrecht in Anspruch nehmen, kann sie sich hierzu jederzeit an einen Mitarbeiter des f\u00fcr die Verarbeitung Verantwortlichen wenden.<\/li>\n<li>\n<h4>c) Recht auf Berichtigung<\/h4>\n<p>Jede von der Verarbeitung personenbezogener Daten betroffene Person hat das vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber gew\u00e4hrte Recht, die unverz\u00fcgliche Berichtigung sie betreffender unrichtiger personenbezogener Daten zu verlangen. Ferner steht der betroffenen Person das Recht zu, unter Ber\u00fccksichtigung der Zwecke der Verarbeitung, die Vervollst\u00e4ndigung unvollst\u00e4ndiger personenbezogener Daten \u2014 auch mittels einer erg\u00e4nzenden Erkl\u00e4rung \u2014 zu verlangen.<\/p>\n<p>M\u00f6chte eine betroffene Person dieses Berichtigungsrecht in Anspruch nehmen, kann sie sich hierzu jederzeit an einen Mitarbeiter des f\u00fcr die Verarbeitung Verantwortlichen wenden.<\/li>\n<li>\n<h4>d) Recht auf L\u00f6schung (Recht auf Vergessen werden)<\/h4>\n<p>Jede von der Verarbeitung personenbezogener Daten betroffene Person hat das vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber gew\u00e4hrte Recht, von dem Verantwortlichen zu verlangen, dass die sie betreffenden personenbezogenen Daten unverz\u00fcglich gel\u00f6scht werden, sofern einer der folgenden Gr\u00fcnde zutrifft und soweit die Verarbeitung nicht erforderlich ist:<\/p>\n<ul style=\"list-style: none;\">\n<li>Die personenbezogenen Daten wurden f\u00fcr solche Zwecke erhoben oder auf sonstige Weise verarbeitet, f\u00fcr welche sie nicht mehr notwendig sind.<\/li>\n<li>Die betroffene Person widerruft ihre Einwilligung, auf die sich die Verarbeitung gem\u00e4\u00df Art. 6 Abs. 1 Buchstabe a DSGVO oder Art. 9 Abs. 2 Buchstabe a DSGVO st\u00fctzte, und es fehlt an einer anderweitigen Rechtsgrundlage f\u00fcr die Verarbeitung.<\/li>\n<li>Die betroffene Person legt gem\u00e4\u00df Art. 21 Abs. 1 DSGVO Widerspruch gegen die Verarbeitung ein, und esliegen keine vorrangigen berechtigten Gr\u00fcnde f\u00fcr die Verarbeitung vor, oder die betroffene Person legt gem\u00e4\u00df Art. 21 Abs. 2 DSGVO Widerspruch gegen die Verarbeitung ein.<\/li>\n<li>Die personenbezogenen Daten wurden unrechtm\u00e4\u00dfig verarbeitet.<\/li>\n<li>Die L\u00f6schung der personenbezogenen Daten ist zur Erf\u00fcllung einer rechtlichen Verpflichtung nach dem Unionsrecht oder dem Recht der Mitgliedstaaten erforderlich, dem der Verantwortliche unterliegt.<\/li>\n<li>Die personenbezogenen Daten wurden in Bezug auf angebotene Dienste der Informationsgesellschaft gem\u00e4\u00df Art. 8 Abs. 1 DSGVO erhoben.<\/li>\n<\/ul>\n<p>Sofern einer der oben genannten Gr\u00fcnde zutrifft und eine betroffene Person die L\u00f6schung von personenbezogenen Daten, die gespeichert sind, veranlassen m\u00f6chte, kann sie sich hierzu jederzeit an einen Mitarbeiter des f\u00fcr die Verarbeitung Verantwortlichen wenden. Der Mitarbeiter wird veranlassen, dass dem L\u00f6schverlangen unverz\u00fcglich nachgekommen wird.<\/p>\n<p>Wurden die personenbezogenen Daten \u00f6ffentlich gemacht und ist unser Unternehmen als Verantwortlicher gem\u00e4\u00df Art. 17 Abs. 1 DSGVO zur L\u00f6schung der personenbezogenen Daten verpflichtet, so trifft uns unter Ber\u00fccksichtigung der verf\u00fcgbaren Technologie und der Implementierungskosten angemessene Ma\u00dfnahmen, auch technischer Art, um andere f\u00fcr die Datenverarbeitung Verantwortliche, welche die ver\u00f6ffentlichten personenbezogenen Daten verarbeiten, dar\u00fcber in Kenntnis zu setzen, dass die betroffene Person von diesen anderen f\u00fcr die Datenverarbeitung Verantwortlichen die L\u00f6schung s\u00e4mtlicherlinks zu diesen personenbezogenen Daten oder von Kopien oder Replikationen dieser personenbezogenen Daten verlangt hat, soweit die Verarbeitung nicht erforderlich ist. Der Mitarbeiter wird im Einzelfall das Notwendige veranlassen.<\/li>\n<li>\n<h4>e) Recht auf Einschr\u00e4nkung der Verarbeitung<\/h4>\n<p>Jede von der Verarbeitung personenbezogener Daten betroffene Person hat das vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber gew\u00e4hrte Recht, von dem Verantwortlichen die Einschr\u00e4nkung der Verarbeitung zu verlangen, wenn eine der folgenden Voraussetzungen gegeben ist:<\/p>\n<ul style=\"list-style: none;\">\n<li>Die Richtigkeit der personenbezogenen Daten wird von der betroffenen Person bestritten, und zwar f\u00fcr eine Dauer, die es dem Verantwortlichen erm\u00f6glicht, die Richtigkeit der personenbezogenen Daten zu \u00fcberpr\u00fcfen.<\/li>\n<li>Die Verarbeitung ist unrechtm\u00e4\u00dfig, die betroffene Person lehnt die L\u00f6schung der personenbezogenen Daten ab und verlangt stattdessen die Einschr\u00e4nkung der Nutzung der personenbezogenen Daten.<\/li>\n<li>Der Verantwortliche ben\u00f6tigt die personenbezogenen Daten f\u00fcr die Zwecke der Verarbeitung nicht l\u00e4nger, die betroffene Person ben\u00f6tigt sie jedoch zur Geltendmachung, Aus\u00fcbung oder Verteidigung von Rechtsanspr\u00fcchen.<\/li>\n<li>Die betroffene Person hat Widerspruch gegen die Verarbeitung gem. Art. 21 Abs. 1 DSGVO eingelegt und es steht noch nicht fest, ob die berechtigten Gr\u00fcnde des Verantwortlichen gegen\u00fcber denen der betroffenen Person \u00fcberwiegen.<\/li>\n<\/ul>\n<p>Sofern eine der oben genannten Voraussetzungen gegeben ist und eine betroffene Person die Einschr\u00e4nkung von personenbezogenen Daten, die gespeichert sind, verlangen m\u00f6chte, kann sie sich hierzu jederzeit an einen Mitarbeiter des f\u00fcr die Verarbeitung Verantwortlichen wenden. Der Mitarbeiter wird die Einschr\u00e4nkung der Verarbeitung veranlassen.<\/li>\n<li>\n<h4>f) Recht auf Daten\u00fcbertragbarkeit<\/h4>\n<p>Jede von der Verarbeitung personenbezogener Daten betroffene Person hat das vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber gew\u00e4hrte Recht, die sie betreffenden personenbezogenen Daten, welche durch die betroffene Person einem Verantwortlichen bereitgestellt wurden, in einem strukturierten, g\u00e4ngigen und maschinenlesbaren Format zu erhalten. Sie hat au\u00dferdem das Recht, diese Daten einem anderen Verantwortlichen ohne Behinderung durch den Verantwortlichen, dem die personenbezogenen Daten bereitgestellt wurden, zu \u00fcbermitteln, sofern die Verarbeitung auf der Einwilligung gem\u00e4\u00df Art. 6 Abs. 1 Buchstabe a DSGVO oder Art. 9 Abs. 2 Buchstabe a DSGVO oder auf einem Vertrag gem\u00e4\u00df Art. 6 Abs. 1 Buchstabe b DSGVO beruht und die Verarbeitung mithilfe automatisierter Verfahren erfolgt, sofern die Verarbeitung nicht f\u00fcr die Wahrnehmung einer Aufgabe erforderlich ist, die im \u00f6ffentlichen Interesseliegt oder in Aus\u00fcbung \u00f6ffentlicher Gewalt erfolgt, welche dem Verantwortlichen \u00fcbertragen wurde.<\/p>\n<p>Ferner hat die betroffene Person bei der Aus\u00fcbung ihres Rechts auf Daten\u00fcbertragbarkeit gem\u00e4\u00df Art. 20 Abs. 1 DSGVO das Recht, zu erwirken, dass die personenbezogenen Daten direkt von einem Verantwortlichen an einen anderen Verantwortlichen \u00fcbermittelt werden, soweit dies technisch machbar ist und sofern hiervon nicht die Rechte und Freiheiten anderer Personen beeintr\u00e4chtigt werden.<\/p>\n<p>Zur Geltendmachung des Rechts auf Daten\u00fcbertragbarkeit kann sich die betroffene Person jederzeit an uns wenden.<\/li>\n<li>\n<h4>g) Recht auf Widerspruch<\/h4>\n<p>Jede von der Verarbeitung personenbezogener Daten betroffene Person hat das vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber gew\u00e4hrte Recht, aus Gr\u00fcnden, die sich aus ihrer besonderen Situation ergeben, jederzeit gegen die Verarbeitung sie betreffender personenbezogener Daten, die aufgrund von Art. 6 Abs. 1 Buchstaben e oder f DSGVO erfolgt, Widerspruch einzulegen. Dies gilt auch f\u00fcr ein auf diese Bestimmungen gest\u00fctztes Profiling.<\/p>\n<p>Wir verarbeiten die personenbezogenen Daten im Falle des Widerspruchs nicht mehr, es sei denn, wir k\u00f6nnen zwingende schutzw\u00fcrdige Gr\u00fcnde f\u00fcr die Verarbeitung nachweisen, die den Interessen, Rechten und Freiheiten der betroffenen Person \u00fcberwiegen, oder die Verarbeitung dient der Geltendmachung, Aus\u00fcbung oder Verteidigung von Rechtsanspr\u00fcchen.<\/p>\n<p>Verarbeiten wir personenbezogene Daten, um Direktwerbung zu betreiben, so hat die betroffene Person das Recht, jederzeit Widerspruch gegen die Verarbeitung der personenbezogenen Daten zum Zwecke derartiger Werbung einzulegen. Dies gilt auch f\u00fcr das Profiling, soweit es mit solcher Direktwerbung in Verbindung steht. Widerspricht die betroffene Person gegen\u00fcber der Verarbeitung f\u00fcr Zwecke der Direktwerbung, so werden wir die personenbezogenen Daten nicht mehr f\u00fcr diese Zwecke verarbeiten.<\/p>\n<p>Zudem hat die betroffene Person das Recht, aus Gr\u00fcnden, die sich aus ihrer besonderen Situation ergeben, gegen die sie betreffende Verarbeitung personenbezogener Daten, die zu wissenschaftlichen oder historischen Forschungszwecken oder zu statistischen Zwecken gem\u00e4\u00df Art. 89 Abs. 1 DSGVO erfolgen, Widerspruch einzulegen, es sei denn, eine solche Verarbeitung ist zur Erf\u00fcllung einer im \u00f6ffentlichen Interesseliegenden Aufgabe erforderlich.<\/p>\n<p>Zur Aus\u00fcbung des Rechts auf Widerspruch kann sich die betroffene Person direkt an jeden Mitarbeiter wenden. Der betroffenen Person steht es ferner frei, im Zusammenhang mit der Nutzung von Diensten der Informationsgesellschaft, ungeachtet der Richtlinie 2002\/58\/EG, ihr Widerspruchsrecht mittels automatisierter Verfahren auszu\u00fcben, bei denen technische Spezifikationen verwendet werden.<\/li>\n<li>\n<h4>h) Automatisierte Entscheidungen im Einzelfall einschlie\u00dflich Profiling<\/h4>\n<p>Jede von der Verarbeitung personenbezogener Daten betroffene Person hat das vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber gew\u00e4hrte Recht, nicht einer ausschlie\u00dflich auf einer automatisierten Verarbeitung \u2014 einschlie\u00dflich Profiling \u2014 beruhenden Entscheidung unterworfen zu werden, die ihr gegen\u00fcber rechtliche Wirkung entfaltet oder sie in \u00e4hnlicher Weise erheblich beeintr\u00e4chtigt, sofern die Entscheidung (1) nicht f\u00fcr den Abschluss oder die Erf\u00fcllung eines Vertrags zwischen der betroffenen Person und dem Verantwortlichen erforderlich ist, oder (2) aufgrund von Rechtsvorschriften der Union oder der Mitgliedstaaten, denen der Verantwortliche unterliegt, zul\u00e4ssig ist und diese Rechtsvorschriften angemessene Ma\u00dfnahmen zur Wahrung der Rechte und Freiheiten sowie der berechtigten Interessen der betroffenen Person enthalten oder (3) mit ausdr\u00fccklicher Einwilligung der betroffenen Person erfolgt.<\/p>\n<p>Ist die Entscheidung (1) f\u00fcr den Abschluss oder die Erf\u00fcllung eines Vertrags zwischen der betroffenen Person und dem Verantwortlichen erforderlich oder (2) erfolgt sie mit ausdr\u00fccklicher Einwilligung der betroffenen Person, triffen wir die angemessene Ma\u00dfnahmen, um die Rechte und Freiheiten sowie die berechtigten Interessen der betroffenen Person zu wahren, wozu mindestens das Recht auf Erwirkung des Eingreifens einer Person seitens des Verantwortlichen, auf Darlegung des eigenen Standpunkts und auf Anfechtung der Entscheidung geh\u00f6rt.<\/p>\n<p>M\u00f6chte die betroffene Person Rechte mit Bezug auf automatisierte Entscheidungen geltend machen, kann sie sich hierzu jederzeit an einen Mitarbeiter des f\u00fcr die Verarbeitung Verantwortlichen wenden.<\/li>\n<li>\n<h4>i) Recht auf Widerruf einer datenschutzrechtlichen Einwilligung<\/h4>\n<p>Jede von der Verarbeitung personenbezogener Daten betroffene Person hat das vom Europ\u00e4ischen Richtlinien- und Verordnungsgeber gew\u00e4hrte Recht, eine Einwilligung zur Verarbeitung personenbezogener Daten jederzeit zu widerrufen.<\/p>\n<p>M\u00f6chte die betroffene Person ihr Recht auf Widerruf einer Einwilligung geltend machen, kann sie sich hierzu jederzeit an einen Mitarbeiter des f\u00fcr die Verarbeitung Verantwortlichen wenden.<\/li>\n<\/ul>\n<h4>Rechtsgrundlage der Verarbeitung<\/h4>\n<p>Art. 6 Ilit. a DSGVO dient unserem Unternehmen als Rechtsgrundlage f\u00fcr Verarbeitungsvorg\u00e4nge, bei denen wir eine Einwilligung f\u00fcr einen bestimmten Verarbeitungszweck einholen. Ist die Verarbeitung personenbezogener Daten zur Erf\u00fcllung eines Vertrags, dessen Vertragspartei die betroffene Person ist, erforderlich, wie dies beispielsweise bei Verarbeitungsvorg\u00e4ngen der Fall ist, die f\u00fcr einelieferung von Waren oder die Erbringung einer sonstigen Leistung oder Gegenleistung notwendig sind, so beruht die Verarbeitung auf Art. 6 Ilit. b DSGVO. Gleiches gilt f\u00fcr solche Verarbeitungsvorg\u00e4nge die zur Durchf\u00fchrung vorvertraglicher Ma\u00dfnahmen erforderlich sind, etwa in F\u00e4llen von Anfragen zur unseren Produkten oder Leistungen. Unterliegt unser Unternehmen einer rechtlichen Verpflichtung durch welche eine Verarbeitung von personenbezogenen Daten erforderlich wird, wie beispielsweise zur Erf\u00fcllung steuerlicher Pflichten, so basiert die Verarbeitung auf Art. 6 Ilit. c DSGVO. In seltenen F\u00e4llen k\u00f6nnte die Verarbeitung von personenbezogenen Daten erforderlich werden, um lebenswichtige Interessen der betroffenen Person oder einer anderen nat\u00fcrlichen Person zu sch\u00fctzen. Dies w\u00e4re beispielsweise der Fall, wenn ein Besucher in unserem Betrieb verletzt werden w\u00fcrde und daraufhin sein Name, sein Alter, seine Krankenkassendaten oder sonstige lebenswichtige Informationen an einen Arzt, ein Krankenhaus oder sonstige Dritte weitergegeben werden m\u00fcssten. Dann w\u00fcrde die Verarbeitung auf Art. 6 Ilit. d DSGVO beruhen.<br \/>\nLetztlich k\u00f6nnten Verarbeitungsvorg\u00e4nge auf Art. 6 Ilit. f DSGVO beruhen. Auf dieser Rechtsgrundlage basieren Verarbeitungsvorg\u00e4nge, die von keiner der vorgenannten Rechtsgrundlagen erfasst werden, wenn die Verarbeitung zur Wahrung eines berechtigten Interesses unseres Unternehmens oder eines Dritten erforderlich ist, sofern die Interessen, Grundrechte und Grundfreiheiten des Betroffenen nicht \u00fcberwiegen. Solche Verarbeitungsvorg\u00e4nge sind uns insbesondere deshalb gestattet, weil sie durch den Europ\u00e4ischen Gesetzgeber besonders erw\u00e4hnt wurden. Er vertrat insoweit die Auffassung, dass ein berechtigtes Interesse anzunehmen sein k\u00f6nnte, wenn die betroffene Person ein Kunde des Verantwortlichen ist (Erw\u00e4gungsgrund 47 Satz 2 DSGVO).<\/p>\n<h4>Berechtigte Interessen an der Verarbeitung, die von dem Verantwortlichen oder einem Dritten verfolgt werden<\/h4>\n<p>Basiert die Verarbeitung personenbezogener Daten auf Artikel 6 Ilit. f DSGVO ist unser berechtigtes Interesse die Durchf\u00fchrung unserer Gesch\u00e4ftst\u00e4tigkeit zugunsten des Wohlergehens all unserer Mitarbeiter und unserer Anteilseigner.<\/p>\n<h4>Dauer, f\u00fcr die die personenbezogenen Daten gespeichert werden<\/h4>\n<p>Das Kriterium f\u00fcr die Dauer der Speicherung von personenbezogenen Daten ist die jeweilige gesetzliche Aufbewahrungsfrist. Nach Ablauf der Frist werden die entsprechenden Daten routinem\u00e4\u00dfig gel\u00f6scht, sofern sie nicht mehr zur Vertragserf\u00fcllung oder Vertragsanbahnung erforderlich sind.<\/p>\n<h4>Gesetzliche oder vertragliche Vorschriften zur Bereitstellung der personenbezogenen Daten; Erforderlichkeit f\u00fcr den Vertragsabschluss; Verpflichtung der betroffenen Person, die personenbezogenen Daten bereitzustellen; m\u00f6gliche Folgen der Nichtbereitstellung<\/h4>\n<p>Wir kl\u00e4ren Sie dar\u00fcber auf, dass die Bereitstellung personenbezogener Daten zum Teil gesetzlich vorgeschrieben ist (z.B. Steuervorschriften) oder sich auch aus vertraglichen Regelungen (z.B. Angaben zum Vertragspartner) ergeben kann.<br \/>\nMitunter kann es zu einem Vertragsschluss erforderlich sein, dass eine betroffene Person uns personenbezogene Daten zur Verf\u00fcgung stellt, die in der Folge durch uns verarbeitet werden m\u00fcssen. Die betroffene Person ist beispielsweise verpflichtet uns personenbezogene Daten bereitzustellen, wenn unser Unternehmen mit ihr einen Vertrag abschlie\u00dft. Eine Nichtbereitstellung der personenbezogenen Daten h\u00e4tte zur Folge, dass der Vertrag mit dem Betroffenen nicht geschlossen werden k\u00f6nnte.<br \/>\nVor einer Bereitstellung personenbezogener Daten durch den Betroffenen muss sich der Betroffene an einen unserer Mitarbeiter wenden. Unser Mitarbeiter kl\u00e4rt den Betroffenen einzelfallbezogen dar\u00fcber auf, ob die Bereitstellung der personenbezogenen Daten gesetzlich oder vertraglich vorgeschrieben oder f\u00fcr den Vertragsabschluss erforderlich ist, ob eine Verpflichtung besteht, die personenbezogenen Daten bereitzustellen, und welche Folgen die Nichtbereitstellung der personenbezogenen Daten h\u00e4tte.<\/p>\n<h4>Bestehen einer automatisierten Entscheidungsfindung<\/h4>\n<p>Als verantwortungsbewusstes Unternehmen verzichten wir auf eine automatische Entscheidungsfindung oder ein Profiling.<\/p>\n<\/div><h3>Allgemeine Cookies<\/h3>\n<p>Die nachfolgenden Cookies z\u00e4hlen zu den technisch notwendigen Cookies.<\/p>\n<p><b>Cookies von WordPress<\/b><\/p>\n<table style=\"width: 100%;\">\n<tbody>\n<tr>\n<th>Name<\/th>\n<th>Zweck<\/th>\n<th>G\u00fcltigkeit<\/th>\n<\/tr>\n<tr>\n<td>wordpress_test_cookie<\/td>\n<td>Dieses Cookie ermittelt, ob die Verwendung von Cookies im Browser deaktiviert wurde. Speicherdauer: Bis zum Ende der Browsersitzung (wird beim Schlie\u00dfen Ihres Internet-Browsers gel\u00f6scht).<\/td>\n<td>Session<\/td>\n<\/tr>\n<tr>\n<td>PHPSESSID<\/td>\n<td>Dieses Cookie speichert Ihre aktuelle Sitzung mit Bezug auf PHP-Anwendungen und gew\u00e4hrleistet so, dass alle Funktionen dieser Website, die auf der PHP-Programmiersprache basieren, vollst\u00e4ndig angezeigt werden k\u00f6nnen. Speicherdauer: Bis zum Ende der Browsersitzung (wird beim Schlie\u00dfen Ihres Internet-Browsers gel\u00f6scht).<\/td>\n<td>Session<\/td>\n<\/tr>\n<tr>\n<td>wordpress_akm_mobile<\/td>\n<td>Diese Cookies werden nur f\u00fcr den Verwaltungsbereich von WordPress verwendet.<\/td>\n<td>1 Jahr<\/td>\n<\/tr>\n<tr>\n<td>wordpress_logged_in_akm_mobile<\/td>\n<td>Diese Cookies werden nur f\u00fcr den Verwaltungsbereich von WordPress verwendet und gelten f\u00fcr andere Seitenbesucher nicht.<\/td>\n<td>Session<\/td>\n<\/tr>\n<tr>\n<td>wp-settings-akm_mobile<\/td>\n<td>Diese Cookies werden nur f\u00fcr den Verwaltungsbereich von WordPress verwendet und gelten f\u00fcr andere Seitenbesucher nicht.<\/td>\n<td>Session<\/td>\n<\/tr>\n<tr>\n<td>wp-settings-time-akm_mobile<\/td>\n<td>Diese Cookies werden nur f\u00fcr den Verwaltungsbereich von WordPress verwendet und gelten f\u00fcr andere Seitenbesucher nicht.<\/td>\n<td>Session<\/td>\n<\/tr>\n<tr>\n<td>ab<\/td>\n<td>wird f\u00fcr A\/B-Tests von neuen Funktionen verwendet.<\/td>\n<td>Session<\/td>\n<\/tr>\n<tr>\n<td>akm_mobile<\/td>\n<td>speichert, ob der Besucher die Mobilversion einer Website angezeigt bekommen m\u00f6chte.<\/td>\n<td>1 Tag<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><p><b>Cookies von WPML<\/b><\/p>\n<table style=\"width:100%\">\n<tr>\n<th>Name<\/th>\n<th>Zweck<\/th>\n<th>G\u00fcltigkeit<\/th>\n<\/tr>\n<tr>\n<td>_icl_current_language<\/td>\n<td>Speichert die vom Benutzer gew\u00e4hlte Sprache.<\/td>\n<td>1 Jahr<\/td>\n<\/tr>\n<tr>\n<td>_icl_visitor_lang_js<\/td>\n<td>Speichert die umgeleitete Sprache beim wechseln der Sprache.<\/td>\n<td>1 Jahr<\/td>\n<\/tr>\n<tr>\n<td>wpml_browser_redirect_test<\/td>\n<td>Dieser Cookie ermittelt, ob die Verwendung von Cookies im Browser deaktiviert wurde. Speicherdauer: Bis zum Ende der Browsersitzung (wird beim Schlie\u00dfen Ihres Internet-Browsers gel\u00f6scht).<\/td>\n<td>1 Jahr<\/td>\n<\/tr>\n<tr>\n<td>wpml_referer_url<\/td>\n<td>Speichert die zuletzt angeforderte URL im Frontend.<\/td>\n<td>1 Jahr<\/td>\n<\/tr>\n<\/table>\n<p><b>Cookies von DSGVO AIO for WordPress<\/b><\/p>\n<table style=\"width:100%\">\n<tr>\n<th>Name<\/th>\n<th>Zweck<\/th>\n<th>G\u00fcltigkeit<\/th>\n<\/tr>\n<tr>\n<td>dsgvoaio<\/td>\n<td>Dieser LocalStorage Key \/ Wert speichert welchen Diensten der Nutzer zugestimmt hat oder nicht.<\/td>\n<td>variabel<\/td>\n<\/tr>\n<tr>\n<td>_uniqueuid<\/td>\n<td>Dieser LocalStorage Key \/ Wert speichert eine generierte ID sodass die Opt-in \/ Opt-out Aktionen des Nutzers dokumentiert werden k\u00f6nnen. Die ID wird anonymisiert gespeichert.<\/td>\n<td>variabel<\/td>\n<\/tr>\n<tr>\n<td>dsgvoaio_create<\/td>\n<td>Dieser LocalStorage Key \/ Wert speichert den Zeitpunkt an dem _uniqueuid generiert wurde.<\/td>\n<td>variabel<\/td>\n<\/tr>\n<tr>\n<td>dsgvoaio_vgwort_disable<\/td>\n<td>Dieser LocalStorage Key \/ Wert speichert ob der Dienst VG Wort Standard zugelassen wird oder nicht (Einstellung des Seitenbetreibers).<\/td>\n<td>variabel<\/td>\n<\/tr>\n<tr>\n<td>dsgvoaio_ga_disable<\/td>\n<td>Dieser LocalStorage Key \/ Wert speichert ob der Dienst Google Analytics Standard zugelassen wird oder nicht (Einstellung des Seitenbetreibers).<\/td>\n<td>variabel<\/td>\n<\/tr>\n<\/table>\n<\/p>\n<\/div>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text]Datenschutzerkl\u00e4rung Stand: 01.03.2022 Wir freuen uns sehr \u00fcber Ihr Interesse an unserem Unternehmen. Datenschutz hat einen besonders hohen Stellenwert f\u00fcr die Gesch\u00e4ftsleitung. Eine Nutzung der Internetseiten ist grunds\u00e4tzlich ohne jede Angabe personenbezogener Daten m\u00f6glich. Sofern eine betroffene Person besondere Services unseres Unternehmens \u00fcber unsere Internetseite in Anspruch nehmen m\u00f6chte, k\u00f6nnte jedoch eine Verarbeitung personenbezogener Daten<br \/><a href=\"https:\/\/boesling.com\/de\/datenschutzerklaerung\/\" class=\"more\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1247","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Datenschutzerkl\u00e4rung - boesling IP<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/boesling.com\/de\/datenschutzerklaerung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Datenschutzerkl\u00e4rung - boesling IP\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column][vc_column_text]Datenschutzerkl\u00e4rung Stand: 01.03.2022 Wir freuen uns sehr \u00fcber Ihr Interesse an unserem Unternehmen. Datenschutz hat einen besonders hohen Stellenwert f\u00fcr die Gesch\u00e4ftsleitung. Eine Nutzung der Internetseiten ist grunds\u00e4tzlich ohne jede Angabe personenbezogener Daten m\u00f6glich. Sofern eine betroffene Person besondere Services unseres Unternehmens \u00fcber unsere Internetseite in Anspruch nehmen m\u00f6chte, k\u00f6nnte jedoch eine Verarbeitung personenbezogener DatenRead more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/boesling.com\/de\/datenschutzerklaerung\/\" \/>\n<meta property=\"og:site_name\" content=\"boesling IP\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-28T16:33:15+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/boesling.com\\\/de\\\/datenschutzerklaerung\\\/\",\"url\":\"https:\\\/\\\/boesling.com\\\/de\\\/datenschutzerklaerung\\\/\",\"name\":\"Datenschutzerkl\u00e4rung - boesling IP\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/boesling.com\\\/#website\"},\"datePublished\":\"2021-08-27T15:02:30+00:00\",\"dateModified\":\"2022-02-28T16:33:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/boesling.com\\\/de\\\/datenschutzerklaerung\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/boesling.com\\\/de\\\/datenschutzerklaerung\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/boesling.com\\\/de\\\/datenschutzerklaerung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/boesling.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Datenschutzerkl\u00e4rung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/boesling.com\\\/#website\",\"url\":\"https:\\\/\\\/boesling.com\\\/\",\"name\":\"boesling IP\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/boesling.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Datenschutzerkl\u00e4rung - boesling IP","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/boesling.com\/de\/datenschutzerklaerung\/","og_locale":"de_DE","og_type":"article","og_title":"Datenschutzerkl\u00e4rung - boesling IP","og_description":"[vc_row][vc_column][vc_column_text]Datenschutzerkl\u00e4rung Stand: 01.03.2022 Wir freuen uns sehr \u00fcber Ihr Interesse an unserem Unternehmen. Datenschutz hat einen besonders hohen Stellenwert f\u00fcr die Gesch\u00e4ftsleitung. Eine Nutzung der Internetseiten ist grunds\u00e4tzlich ohne jede Angabe personenbezogener Daten m\u00f6glich. Sofern eine betroffene Person besondere Services unseres Unternehmens \u00fcber unsere Internetseite in Anspruch nehmen m\u00f6chte, k\u00f6nnte jedoch eine Verarbeitung personenbezogener DatenRead more","og_url":"https:\/\/boesling.com\/de\/datenschutzerklaerung\/","og_site_name":"boesling IP","article_modified_time":"2022-02-28T16:33:15+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/boesling.com\/de\/datenschutzerklaerung\/","url":"https:\/\/boesling.com\/de\/datenschutzerklaerung\/","name":"Datenschutzerkl\u00e4rung - boesling IP","isPartOf":{"@id":"https:\/\/boesling.com\/#website"},"datePublished":"2021-08-27T15:02:30+00:00","dateModified":"2022-02-28T16:33:15+00:00","breadcrumb":{"@id":"https:\/\/boesling.com\/de\/datenschutzerklaerung\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/boesling.com\/de\/datenschutzerklaerung\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/boesling.com\/de\/datenschutzerklaerung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/boesling.com\/de\/"},{"@type":"ListItem","position":2,"name":"Datenschutzerkl\u00e4rung"}]},{"@type":"WebSite","@id":"https:\/\/boesling.com\/#website","url":"https:\/\/boesling.com\/","name":"boesling IP","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/boesling.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/boesling.com\/de\/wp-json\/wp\/v2\/pages\/1247","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boesling.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/boesling.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/boesling.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/boesling.com\/de\/wp-json\/wp\/v2\/comments?post=1247"}],"version-history":[{"count":5,"href":"https:\/\/boesling.com\/de\/wp-json\/wp\/v2\/pages\/1247\/revisions"}],"predecessor-version":[{"id":1483,"href":"https:\/\/boesling.com\/de\/wp-json\/wp\/v2\/pages\/1247\/revisions\/1483"}],"wp:attachment":[{"href":"https:\/\/boesling.com\/de\/wp-json\/wp\/v2\/media?parent=1247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}